{"id":131,"date":"2019-08-24T12:11:39","date_gmt":"2019-08-24T12:11:39","guid":{"rendered":"https:\/\/gm.faith-time.com\/?p=131"},"modified":"2019-11-01T21:53:56","modified_gmt":"2019-11-01T21:53:56","slug":"19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit","status":"publish","type":"post","link":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/","title":{"rendered":"19.01.2018  &#8220;Jesus unschuldig am Kreuz &#8211; Wo bleibt die Gerechtigkeit?&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Was war da eigentlich los, als Jesus vor 2000 Jahren in Jerusalem hingerichtet wurde und eines grausamen Kreuzestodes starb? Lassen Sie sich mitrei\u00dfen von einem wirklich ersch\u00fctternden sowie ergreifenden Thema. Im Anschluss gibt es noch ein leckeres Abendessen. Dabei freuen wir uns auf den Austausch mit Ihnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Adresse<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Adresse ist:<br>Bornerhof 8-10<br>51643 Gummersbach<\/p>\n\n\n\n<div style=\"width: 100%;position: relative;\"><iframe loading=\"lazy\" width=\"100%\" height=\"440\" src=\"https:\/\/maps.google.com\/maps?width=700&amp;height=440&amp;hl=en&amp;q=Bornerhof%208%2C%20Gummersbach+(Adresse)&amp;ie=UTF8&amp;t=&amp;z=17&amp;iwloc=B&amp;output=embed\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"><\/iframe><\/div><br>\n\n\n\n<h3 class=\"wp-block-heading\">Zeiten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Termin beginnt um <strong>19:00<\/strong>.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dokumente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">zu diesem Termine sind keine Dokumente verf\u00fcgbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was war da eigentlich los, als Jesus vor 2000 Jahren in Jerusalem hingerichtet wurde und eines grausamen Kreuzestodes starb? Lassen Sie sich [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[12],"tags":[],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-termine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>19.01.2018 &quot;Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?&quot; - Faith Time<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"19.01.2018 &quot;Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?&quot; - Faith Time\" \/>\n<meta property=\"og:description\" content=\"Was war da eigentlich los, als Jesus vor 2000 Jahren in Jerusalem hingerichtet wurde und eines grausamen Kreuzestodes starb? Lassen Sie sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Faith Time\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-24T12:11:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-01T21:53:56+00:00\" \/>\n<meta name=\"author\" content=\"Christoph\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christoph\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/\"},\"author\":{\"name\":\"Christoph\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/#\\\/schema\\\/person\\\/fa5ac591dd49bb66848555751ac4fde0\"},\"headline\":\"19.01.2018 &#8220;Jesus unschuldig am Kreuz &#8211; Wo bleibt die Gerechtigkeit?&#8221;\",\"datePublished\":\"2019-08-24T12:11:39+00:00\",\"dateModified\":\"2019-11-01T21:53:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/\"},\"wordCount\":78,\"commentCount\":0,\"articleSection\":[\"Termine\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/\",\"url\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/\",\"name\":\"19.01.2018 \\\"Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?\\\" - Faith Time\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/#website\"},\"datePublished\":\"2019-08-24T12:11:39+00:00\",\"dateModified\":\"2019-11-01T21:53:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/#\\\/schema\\\/person\\\/fa5ac591dd49bb66848555751ac4fde0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/2019\\\/08\\\/24\\\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gm.faith-time.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"19.01.2018 &#8220;Jesus unschuldig am Kreuz &#8211; Wo bleibt die Gerechtigkeit?&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/#website\",\"url\":\"https:\\\/\\\/gm.faith-time.com\\\/\",\"name\":\"Faith Time\",\"description\":\"Gummersbach\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gm.faith-time.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gm.faith-time.com\\\/#\\\/schema\\\/person\\\/fa5ac591dd49bb66848555751ac4fde0\",\"name\":\"Christoph\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g\",\"caption\":\"Christoph\"},\"url\":\"https:\\\/\\\/gm.faith-time.com\\\/index.php\\\/author\\\/christoph\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"19.01.2018 \"Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?\" - Faith Time","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/","og_locale":"de_DE","og_type":"article","og_title":"19.01.2018 \"Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?\" - Faith Time","og_description":"Was war da eigentlich los, als Jesus vor 2000 Jahren in Jerusalem hingerichtet wurde und eines grausamen Kreuzestodes starb? Lassen Sie sich [&hellip;]","og_url":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/","og_site_name":"Faith Time","article_published_time":"2019-08-24T12:11:39+00:00","article_modified_time":"2019-11-01T21:53:56+00:00","author":"Christoph","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christoph"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/#article","isPartOf":{"@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/"},"author":{"name":"Christoph","@id":"https:\/\/gm.faith-time.com\/#\/schema\/person\/fa5ac591dd49bb66848555751ac4fde0"},"headline":"19.01.2018 &#8220;Jesus unschuldig am Kreuz &#8211; Wo bleibt die Gerechtigkeit?&#8221;","datePublished":"2019-08-24T12:11:39+00:00","dateModified":"2019-11-01T21:53:56+00:00","mainEntityOfPage":{"@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/"},"wordCount":78,"commentCount":0,"articleSection":["Termine"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/","url":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/","name":"19.01.2018 \"Jesus unschuldig am Kreuz - Wo bleibt die Gerechtigkeit?\" - Faith Time","isPartOf":{"@id":"https:\/\/gm.faith-time.com\/#website"},"datePublished":"2019-08-24T12:11:39+00:00","dateModified":"2019-11-01T21:53:56+00:00","author":{"@id":"https:\/\/gm.faith-time.com\/#\/schema\/person\/fa5ac591dd49bb66848555751ac4fde0"},"breadcrumb":{"@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gm.faith-time.com\/index.php\/2019\/08\/24\/19-01-2018-jesus-unschuldig-am-kreuz-wo-bleibt-die-gerechtigkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gm.faith-time.com\/"},{"@type":"ListItem","position":2,"name":"19.01.2018 &#8220;Jesus unschuldig am Kreuz &#8211; Wo bleibt die Gerechtigkeit?&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/gm.faith-time.com\/#website","url":"https:\/\/gm.faith-time.com\/","name":"Faith Time","description":"Gummersbach","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gm.faith-time.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/gm.faith-time.com\/#\/schema\/person\/fa5ac591dd49bb66848555751ac4fde0","name":"Christoph","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88ca6a30550bf08f3e2cd1ee97443ffb31fb6ea5c93bf1d2e665b430a9302ccf?s=96&d=mm&r=g","caption":"Christoph"},"url":"https:\/\/gm.faith-time.com\/index.php\/author\/christoph\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":2,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"predecessor-version":[{"id":205,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/posts\/131\/revisions\/205"}],"wp:attachment":[{"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gm.faith-time.com\/index.php\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}